{"id":669,"date":"2020-06-08T13:28:50","date_gmt":"2020-06-08T05:28:50","guid":{"rendered":"https:\/\/luckywoodtw.com\/?page_id=669"},"modified":"2020-06-19T12:55:50","modified_gmt":"2020-06-19T04:55:50","slug":"contact","status":"publish","type":"page","link":"https:\/\/luckywoodtw.com\/en\/contact\/","title":{"rendered":"CONTACT"},"content":{"rendered":"\n\n  <div class=\"banner has-hover\" id=\"banner-722110815\">\n          <div class=\"banner-inner fill\">\n        <div class=\"banner-bg fill\" >\n            <img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/luckywoodtw.com\/wp-content\/uploads\/2020\/05\/flatsomebilder-10-of-10.jpg\" class=\"bg attachment-original size-original\" alt=\"\u684c\u677f\" \/>                                    \n                    <\/div>\n\t\t\n        <div class=\"banner-layers container\">\n            <div class=\"fill banner-link\"><\/div>            \n\n\n        <\/div>\n      <\/div>\n\n            \n<style>\n#banner-722110815 {\n  padding-top: 550px;\n}\n#banner-722110815 .banner-bg img {\n  object-position: 71% 69%;\n}\n<\/style>\n  <\/div>\n\n\n\n\t<section class=\"section\" id=\"section_294983332\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n\n\t<div id=\"gap-419623945\" class=\"gap-element clearfix\" style=\"display:block; height:auto;\">\n\t\t\n<style>\n#gap-419623945 {\n  padding-top: 40px;\n}\n<\/style>\n\t<\/div>\n\t\n\n<div class=\"row align-center\"  id=\"row-1413350510\">\n\n\n\t<div id=\"col-963722144\" class=\"col medium-4 small-10 large-4\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n<h1 class=\"uppercase\"><strong><span style=\"font-size: 150%;\">CONTACT US<\/span><\/strong><\/h1>\n<p><span style=\"color: #a86047;\">\u6797\u7199\u570b\u969b\u6709\u9650\u516c\u53f8<\/span><br \/>T\uff1a+886-4-2358-7889<br \/>E\uff1a<a href=\"mailto:info@luckywoodtw.com\">info@luckywoodtw.com<\/a><br \/>No. 12, Yucheng Rd., Xitun Dist., Taichung City 407, Taiwan (R.O.C.)<\/p>\n<div class=\"social-icons follow-icons full-width text-left\" ><a href=\"http:\/\/x\" target=\"_blank\" data-label=\"Facebook\" class=\"icon button circle is-outline tooltip facebook\" title=\"Follow on Facebook\" aria-label=\"Follow on Facebook\" rel=\"noopener nofollow\"><i class=\"icon-facebook\" aria-hidden=\"true\"><\/i><\/a><a href=\"http:\/\/x\" target=\"_blank\" data-label=\"Instagram\" class=\"icon button circle is-outline tooltip instagram\" title=\"Follow on Instagram\" aria-label=\"Follow on Instagram\" rel=\"noopener nofollow\"><i class=\"icon-instagram\" aria-hidden=\"true\"><\/i><\/a><a href=\"http:\/\/x\" data-label=\"Twitter\" target=\"_blank\" class=\"icon button circle is-outline tooltip twitter\" title=\"Follow on Twitter\" aria-label=\"Follow on Twitter\" rel=\"noopener nofollow\"><i class=\"icon-twitter\" aria-hidden=\"true\"><\/i><\/a><a href=\"mailto:info@luckywoodtw.com\" data-label=\"E-mail\" target=\"_blank\" class=\"icon button circle is-outline tooltip email\" title=\"Send us an email\" aria-label=\"Send us an email\" rel=\"nofollow noopener\"><i class=\"icon-envelop\" aria-hidden=\"true\"><\/i><\/a><a href=\"tel:886425207711\" data-label=\"Phone\" target=\"_blank\" class=\"icon button circle is-outline tooltip phone\" title=\"Call us\" aria-label=\"Call us\" rel=\"nofollow noopener\"><i class=\"icon-phone\" aria-hidden=\"true\"><\/i><\/a><a href=\"http:\/\/x\" data-label=\"Pinterest\" target=\"_blank\" class=\"icon button circle is-outline tooltip pinterest\" title=\"Follow on Pinterest\" aria-label=\"Follow on Pinterest\" rel=\"noopener nofollow\"><i class=\"icon-pinterest\" aria-hidden=\"true\"><\/i><\/a><\/div>\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1529851723\" class=\"col medium-8 small-10 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\n\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f1787-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"1787\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/en\/wp-json\/wp\/v2\/pages\/669#wpcf7-f1787-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"1787\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.7\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f1787-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-flat\">\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Name\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"E-Mail\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"tel-301\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-tel wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-tel\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Phone Number\" value=\"\" type=\"tel\" name=\"tel-301\" \/><\/span>\n\t<\/p>\n\t<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"Message\" name=\"your-message\"><\/textarea><\/span>\n\t<\/p>\n\t<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner button\" type=\"submit\" value=\"SEND\" \/>\n\t<\/p>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n\n\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n<\/div>\n\n\t\t<\/div>\n\n\t\t\n<style>\n#section_294983332 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-669","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/pages\/669","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/comments?post=669"}],"version-history":[{"count":4,"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/pages\/669\/revisions"}],"predecessor-version":[{"id":1049,"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/pages\/669\/revisions\/1049"}],"wp:attachment":[{"href":"https:\/\/luckywoodtw.com\/en\/wp-json\/wp\/v2\/media?parent=669"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}